{"id":98507,"date":"2025-01-15T11:03:47","date_gmt":"2025-01-15T10:03:47","guid":{"rendered":"https:\/\/sysdil.es\/producto\/antihurto-y-rfid-antenas-a-de-deteccion-a-techo\/"},"modified":"2026-07-14T15:07:44","modified_gmt":"2026-07-14T13:07:44","slug":"antihurto-y-rfid-antenas-a-de-deteccion-a-techo","status":"publish","type":"product","link":"https:\/\/sysdil.es\/pt-pt\/producto\/antihurto-y-rfid-antenas-a-de-deteccion-a-techo\/","title":{"rendered":"RFID Antenas Antihurto a techo"},"content":{"rendered":"<p>Tiene lectura RFID y funci\u00f3n de alarma.<br \/>\n\u00b7 Tiene dise\u00f1o compacto con alarma interior e indicaci\u00f3n LED. El volumen del timbre se puede configurar m\u00e1s bajo o m\u00e1s alto.<br \/>\n\u00b7 Con instalaci\u00f3n de fijador, se cuelga del techo o pared de la entrada de la tienda.<br \/>\n\u00b7 Ajuste flexible del ancho de detecci\u00f3n. <strong>La detecci\u00f3n m\u00e1xima alcanza los 10 m.<\/strong><br \/>\n\u00b7 Los usuarios pueden configurar c\u00f3digos EPC exclusivos para etiquetas\/etiquetas, por lo que NOVEL-812 detectar\u00e1 solo c\u00f3digos EPC asignados. Eso significa que s\u00f3lo las etiquetas con c\u00f3digos EPC exclusivos activar\u00e1n la alarma NOVEL-812, por lo tanto 0 se produjo una falsa alarma.<br \/>\n\u00b7 Se ofrece software SDK, se puede desarrollar a\u00fan m\u00e1s la gesti\u00f3n inteligente de inventario.<\/p>\n<p>\u00b7 Aplicaci\u00f3n sencilla<br \/>\nSe utiliza \u00fanicamente para alarma antirrobo y funciona independientemente del POS o del sistema de control de inventario.<br \/>\n<span style=\"color: #00768f;\"><strong>Si los productos impagos salen de la tienda, NOVEL-812 saltar\u00e1 la alarma.<\/strong><\/span><br \/>\n<span style=\"color: #00768f;\"><strong>Si los productos pagados salen de la tienda, NOVEL-812 no saltar\u00e1<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>\u00b7 Instalaci\u00f3n y puesta en marcha sencilla<\/strong><br \/>\nSe utiliza \u00fanicamente para alarma antirrobo y funciona independientemente del POS o del sistema de control de inventario.<br \/>\nSi los productos impagos salen de la tienda, NOVEL-812 dar\u00e1 la alarma.<br \/>\nSi los productos pagados salen de la tienda, NOVEL-812 no dar\u00e1 alarma.<br \/>\n<strong>Una ampl\u00eda gama de etiquetas de protecci\u00f3n: <\/strong><br \/>\n<strong>Etiquetas Adhesivas &#8211; Etiquetas R\u00edgidas para prendas, para botellas, para gafas<\/strong><\/p>\n<p><span style=\"color: #00768f;\"><strong>Compatible con la plataforma \u00a0de gesti\u00f3n de Inventario por RFID<br \/>\n<\/strong><\/span><br \/>\n<a href=\"https:\/\/sysdil.es\/sysventory\/\"><img decoding=\"async\" class=\"wp-image-98586 aligncenter\" src=\"https:\/\/sysdil.es\/wp-content\/uploads\/2025\/01\/Logo_sysventory_small-R.webp\" alt=\"\" width=\"270\" height=\"48\" srcset=\"https:\/\/sysdil.es\/wp-content\/uploads\/2025\/01\/Logo_sysventory_small-R-200x36.webp 200w, https:\/\/sysdil.es\/wp-content\/uploads\/2025\/01\/Logo_sysventory_small-R-300x53.webp 300w, https:\/\/sysdil.es\/wp-content\/uploads\/2025\/01\/Logo_sysventory_small-R-400x71.webp 400w, https:\/\/sysdil.es\/wp-content\/uploads\/2025\/01\/Logo_sysventory_small-R.webp 500w\" sizes=\"(max-width: 270px) 100vw, 270px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #808080;\"><strong>SOLICITAR INFORMACI\u00d3N:<\/strong><\/span><\/p>\n<p><strong><span style=\"color: #00768f;\"><a style=\"color: #00768f;\" title=\"Sistema RFID a Techo\" href=\"https:\/\/sysdil.es\/pt-pt\/contate-nos\/\">Contacta con nosotros<\/a><\/span><\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-98621\" src=\"https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo.webp\" alt=\"\" width=\"720\" height=\"479\" srcset=\"https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo-200x133.webp 200w, https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo-300x199.webp 300w, https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo-400x266.webp 400w, https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo-500x332.webp 500w, https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo-600x399.webp 600w, https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo-700x465.webp 700w, https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo-768x511.webp 768w, https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo-800x532.webp 800w, https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo-1024x681.webp 1024w, https:\/\/sysdil.es\/wp-content\/uploads\/2026\/05\/Entrada-RFID_Conteo.webp 1149w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n","protected":false},"featured_media":98539,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[279,268,295,297],"product_tag":[194,275,280,276],"class_list":["post-98507","product","type-product","status-publish","has-post-thumbnail","product_cat-rfid","product_cat-sistemas-antihurto","product_cat-sisrfid","product_cat-sysrfid","product_tag-antifurto","product_tag-farmacias","product_tag-moda","product_tag-perfumerias","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/sysdil.es\/pt-pt\/wp-json\/wp\/v2\/product\/98507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sysdil.es\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sysdil.es\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sysdil.es\/pt-pt\/wp-json\/wp\/v2\/comments?post=98507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sysdil.es\/pt-pt\/wp-json\/wp\/v2\/media\/98539"}],"wp:attachment":[{"href":"https:\/\/sysdil.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=98507"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sysdil.es\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=98507"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sysdil.es\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=98507"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sysdil.es\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=98507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}